{"id":3711,"date":"2021-02-26T16:35:10","date_gmt":"2021-02-26T14:35:10","guid":{"rendered":"https:\/\/lerevebeauty.it\/glossary\/"},"modified":"2023-12-11T12:16:41","modified_gmt":"2023-12-11T10:16:41","slug":"glossary","status":"publish","type":"page","link":"https:\/\/lerevebeauty.it\/en\/glossary\/","title":{"rendered":"Glossary"},"content":{"rendered":"<div id=\"modal-ready\">\n<p class=\"wp-block-paragraph\"><strong><div class=\"glossary-term-bar\"><span class=\"glossary-link-initial-item\"><a href=\"#a\">a<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#b\">b<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#c\">c<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#d\">d<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#e\">e<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#f\">f<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#g\">g<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#h\">h<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#i\">i<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#j\">j<\/a><\/span><span class=\"glossary-no-link-initial-item\">k<\/span><span class=\"glossary-link-initial-item\"><a href=\"#l\">l<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#m\">m<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#n\">n<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#o\">o<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#p\">p<\/a><\/span><span class=\"glossary-no-link-initial-item\">q<\/span><span class=\"glossary-link-initial-item\"><a href=\"#r\">r<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#s\">s<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#t\">t<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#u\">u<\/a><\/span><span class=\"glossary-link-initial-item\"><a href=\"#v\">v<\/a><\/span><span class=\"glossary-no-link-initial-item\">w<\/span><span class=\"glossary-no-link-initial-item\">x<\/span><span class=\"glossary-no-link-initial-item\">y<\/span><span class=\"glossary-link-initial-item\"><a href=\"#z\">z<\/a><\/span><\/div><div class=\"glossary-term-list grid\"><div class=\"glossary-block glossary-block-a\"><span class=\"glossary-letter\" id=\"a\">a<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/acetilcisteina\/\">Acetilcisteina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/aloe-barbadensis-leaf-juice-succo-di-aloe-vera\/\">Aloe barbadensis leaf juice (Succo di Aloe Vera)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/amyl-cinnamal\/\">Amyl cinnamal<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ascorbyl-palmitate-vitamina-c%ef%bf%bc\/\">Ascorbyl palmitate (Vitamina C)\ufffc<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/astaxantina\/\">Astaxantina<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-b\"><span class=\"glossary-letter\" id=\"b\">b<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/bardana\/\">Bardana<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/benzyl-alcohol\/\">Benzyl alcohol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/benzyl-cinnamate\/\">Benzyl cinnamate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/benzyl-salicylate\/\">Benzyl salicylate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/betacarotene\/\">Betacarotene<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/bisabolol\/\">Bisabolol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/borago-officinalis-seed-oil-olio-di-borragine\/\">Borago officinalis seed oil (Olio di Borragine)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-c\"><span class=\"glossary-letter\" id=\"c\">c<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/c13-14-isoparaffin\/\">C13-14 isoparaffin<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/cannabis-sativa-seed-oil-olio-di-canapa\/\">Cannabis sativa seed oil (Olio di Canapa)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/caprylic-capric-triglyceride\/\">Caprylic\/capric triglyceride<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/cardo-mariano\/\">Cardo Mariano<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/carnosine-carnosina\/\">Carnosine (Carnosina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/centella-asiatica-extract\/\">Centella Asiatica Extract<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/cetearyl-alcohol\/\">Cetearyl alcohol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/cetearyl-ethylhexanoate\/\">Cetearyl ethylhexanoate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/cetearyl-glucoside\/\">Cetearyl glucoside<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/chamomilla-recutita-flower-extract-estratto-di-camomilla\/\">Chamomilla recutita  flower extract (Estratto di Camomilla)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/citral\/\">Citral<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/citric-acid\/\">Citric acid<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/citrus-aurantium-amara-flower-oil-olio-di-fiori-di-neroli\/\">Citrus aurantium amara flower oil (Olio di fiori di Neroli)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-d\"><span class=\"glossary-letter\" id=\"d\">d<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/daidzein-daidzeina\/\">Daidzein (Daidzeina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/decyl-glucoside\/\">Decyl glucoside<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/dicaprylyl-etere\/\">Dicaprylyl etere<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/disodium-cocoamphodiacetate\/\">Disodium cocoamphodiacetate<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-e\"><span class=\"glossary-letter\" id=\"e\">e<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ethoxydiglycol\/\">Ethoxydiglycol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ethylhexyl-stearate\/\">Ethylhexyl stearate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ethylhexylglycerin\/\">Ethylhexylglycerin<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/eugenol\/\">Eugenol<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-f\"><span class=\"glossary-letter\" id=\"f\">f<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/farnesol\/\">Farnesol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/fitosteroli\/\">Fitosteroli<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-g\"><span class=\"glossary-letter\" id=\"g\">g<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/genistein-genisteina\/\">Genistein (Genisteina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/geraniol\/\">Geraniol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/gluconato-di-rame\/\">Gluconato di rame<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/gluconolactone-gluconolattone\/\">Gluconolactone (Gluconolattone)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/glucose-glucosio\/\">Glucose (Glucosio)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/glycerin\/\">Glycerin<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/glyceryl-stearate-se\/\">Glyceryl stearate SE<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/glycine-glicina\/\">Glycine (Glicina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/glycine-soja-extract-estratto-di-soia-glicina\/\">Glycine soja extract (Estratto di Soia Glicina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/gossypium-herbaceum-seed-oil-olio-di-semi-di-cotone\/\">Gossypium herbaceum seed oil (Olio di semi di Cotone)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-h\"><span class=\"glossary-letter\" id=\"h\">h<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hamamelis-virginiana-leaf-extract-estratto-di-amamelide\/\">Hamamelis virginiana leaf extract (Estratto di Amamelide)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/helianthus-annuus-seed-oil-olio-di-semi-di-girasole\/\">Helianthus annuus  seed oil (Olio di semi di Girasole)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydrogenated-ethylhexyl-olivate\/\">Hydrogenated ethylhexyl olivate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydrogenated-olive-oil-unsaponifiables\/\">Hydrogenated olive oil unsaponifiables<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydrogenated-polyisobutene\/\">Hydrogenated polyisobutene<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydrolyzed-collagen-collagene-idrolizzato\/\">Hydrolyzed collagen (Collagene Idrolizzato)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydrolyzed-wheat-protein-proteine-del-grano-idrolizzate\/\">Hydrolyzed wheat protein (Proteine del Grano Idrolizzate)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydroxyethyl-acrylate-sodium-acryloyldimethyl-taurate-copolymer\/\">Hydroxyethyl acrylate\/sodium acryloyldimethyl taurate copolymer<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/hydroxytyrosol-idrossitirosolo\/\">Hydroxytyrosol (Idrossitirosolo)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-i\"><span class=\"glossary-letter\" id=\"i\">i<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/idrossipropilmetilcellulosa\/\">Idrossipropilmetilcellulosa<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/isoamyl-cocoate\/\">Isoamyl cocoate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/isoamyl-laurate\/\">Isoamyl Laurate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/isopropyl-myristate\/\">Isopropyl myristate<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-j\"><span class=\"glossary-letter\" id=\"j\">j<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/jasminum-officinale-flower-oil-olio-di-fiori-di-gelsomino\/\">Jasminum officinale flower oil (Olio di fiori di Gelsomino)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-l\"><span class=\"glossary-letter\" id=\"l\">l<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/l-cistina\/\">L-Cistina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/l-metionina\/\">L-Metionina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/l-teanina\/\">L-Teanina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/l-tirosina\/\">L-Tirosina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/lactic-acid-acido-lattico\/\">Lactic acid (Acido Lattico)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/lactobionic-acid-acido-lattobionico\/\">Lactobionic acid (Acido Lattobionico)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/laureth-7\/\">Laureth-7<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/lauryl-glucoside\/\">Lauryl glucoside<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/lecithin-lecitina\/\">Lecithin (Lecitina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/licopene\/\">Licopene<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/limonene\/\">Limonene<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/linalool\/\">Linalool<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/linum-usitatissimum-seed-oil-olio-di-semi-di-lino\/\">Linum usitatissimum seed oil (Olio di semi di Lino)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/luteina\/\">Luteina<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-m\"><span class=\"glossary-letter\" id=\"m\">m<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/magnesio-stearato-vegetale\/\">Magnesio stearato vegetale<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/maitake\/\">Maitake<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/maltodextrin-maltodestrina\/\">Maltodextrin (Maltodestrina)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/malva-sylvestris-leaf-extract-estratto-di-malva\/\">Malva sylvestris leaf extract (Estratto di Malva)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/melatonina\/\">Melatonina<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/miglio\/\">Miglio<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-n\"><span class=\"glossary-letter\" id=\"n\">n<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/niacinamide\/\">Niacinamide<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-o\"><span class=\"glossary-letter\" id=\"o\">o<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/olea-europaea-fruit-oil-olio-extravergine-doliva\/\">Olea europaea fruit oil (Olio Extravergine d\u2019Oliva)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/olea-europaea-oil-unsaponifiables-olio-di-oliva-insaponificabile\/\">Olea europaea oil unsaponifiables (Olio di Oliva Insaponificabile)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ortica-urtica-dioica-l\/\">Ortica (Urtica dioica L.)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-p\"><span class=\"glossary-letter\" id=\"p\">p<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/panax-ginseng-root-extract-ginseng\/\">Panax Ginseng Root Extract (Ginseng)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/panthenol-pantenolo\/\">Panthenol (Pantenolo)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/peg-40-castor-oil\/\">PEG-40 castor oil<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/persea-gratissima-oil-olio-di-avocado\/\">Persea gratissima oil (Olio di Avocado)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/phenethyl-alcohol\/\">Phenethyl alcohol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/phenoxyethanol\/\">Phenoxyethanol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/phyllantus-amarus\/\">Phyllantus amarus<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/picrorhiza-kurroa\/\">Picrorhiza kurroa<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/piper-nigrum-l-pepe-nero\/\">Piper Nigrum L. (Pepe nero)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/polygonum-multiflorum\/\">Polygonum multiflorum<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/potassium-cetyl-phosphate\/\">Potassium cetyl phosphate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/propylene-glycol\/\">Propylene glycol<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/prunus-amygdalus-dulcis-oil-olio-di-mandorle-dolci\/\">Prunus amygdalus dulcis oil (Olio di Mandorle Dolci)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/prunus-armeniaca-kernel-oil-olio-di-nocciolo-di-albicocca\/\">Prunus armeniaca kernel oil (Olio di nocciolo di Albicocca)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-r\"><span class=\"glossary-letter\" id=\"r\">r<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/resveratrolo\/\">Resveratrolo<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ribes-nigrum-fruit-oil-olio-di-ribes-nero\/\">Ribes nigrum fruit oil (Olio di Ribes Nero)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/rosa-damascena-flower-extract-estratto-di-fiori-di-rosa-damascena\/\">Rosa damascena flower extract (Estratto di fiori di Rosa Damascena)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-s\"><span class=\"glossary-letter\" id=\"s\">s<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/silice-colloidale-anidra\/\">Silice colloidale anidra<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/simmondsia-chinensis-seed-oil-olio-di-jojoba\/\">Simmondsia chinensis seed oil (Olio di Jojoba)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/sodio-amido-glicolato\/\">Sodio amido glicolato<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/sodium-dehydroacetate\/\">Sodium dehydroacetate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/sodium-glutamate\/\">Sodium glutamate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/sodium-pca\/\">Sodium PCA<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/sorbitol-sorbitolo\/\">Sorbitol (Sorbitolo)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/soy-isoflavones-isoflavoni-di-soia\/\">Soy isoflavones (Isoflavoni di soia)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/stearyl-alcohol\/\">Stearyl alcohol<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-t\"><span class=\"glossary-letter\" id=\"t\">t<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/tetrasodium-glutamate-diacetate\/\">Tetrasodium glutamate diacetate<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/thioctic-acid-acido-lipoico\/\">Thioctic Acid (Acido Lipoico)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/tocopherol-vitamina-e\/\">Tocopherol (Vitamina E)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/tocopheryl-acetate-estere-della-vitamina-e\/\">Tocopheryl acetate (estere della Vitamina E)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/\">Triticum vulgare germ oil (Olio di Germe di Grano)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-u\"><span class=\"glossary-letter\" id=\"u\">u<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/ubidecarenone-coenzima-q10\/\">Ubidecarenone (Coenzima Q10)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/urea\/\">Urea<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-v\"><span class=\"glossary-letter\" id=\"v\">v<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/vitamina-b6\/\">Vitamina B6<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/vitamina-c-acido-l-ascorbico\/\">Vitamina C (Acido L-ascorbico)<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/vitamina-e\/\">Vitamina E<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/vitis-biocomplex-m\/\">Vitis biocomplex M<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/vitis-vinifera-seed-oil-olio-di-vinaccioli\/\">Vitis vinifera seed oil (Olio di Vinaccioli)<\/a><\/span><\/li><\/ul><\/div><div class=\"glossary-block glossary-block-z\"><span class=\"glossary-letter\" id=\"z\">z<\/span><ul><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/zafferano\/\">Zafferano<\/a><\/span><\/li><li><span class=\"glossary-link-item\"><a href=\"https:\/\/lerevebeauty.it\/en\/glossario\/zinco\/\">Zinco<\/a><\/span><\/li><\/ul><\/div><\/div><\/strong><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"_joinchat":[],"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-3711","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glossary - Ler\u00e8ve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lerevebeauty.it\/en\/glossary\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glossary - Ler\u00e8ve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lerevebeauty.it\/en\/glossary\/\" \/>\n<meta property=\"og:site_name\" content=\"Ler\u00e8ve\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T10:16:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossary\\\/\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossary\\\/\",\"name\":\"Glossary - Ler\u00e8ve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#website\"},\"datePublished\":\"2021-02-26T14:35:10+00:00\",\"dateModified\":\"2023-12-11T10:16:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossary\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossary\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\",\"name\":\"Ler\u00e8ve\",\"description\":\"Nutricosmetics &amp; Beauty\",\"publisher\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#organization\",\"name\":\"Ler\u00e8ve\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo-lereve-senza-payoff.png\",\"contentUrl\":\"https:\\\/\\\/lerevebeauty.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo-lereve-senza-payoff.png\",\"width\":377,\"height\":110,\"caption\":\"Ler\u00e8ve\"},\"image\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glossary - Ler\u00e8ve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lerevebeauty.it\/en\/glossary\/","og_locale":"en_US","og_type":"article","og_title":"Glossary - Ler\u00e8ve","og_url":"https:\/\/lerevebeauty.it\/en\/glossary\/","og_site_name":"Ler\u00e8ve","article_modified_time":"2023-12-11T10:16:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lerevebeauty.it\/en\/glossary\/","url":"https:\/\/lerevebeauty.it\/en\/glossary\/","name":"Glossary - Ler\u00e8ve","isPartOf":{"@id":"https:\/\/lerevebeauty.it\/en\/#website"},"datePublished":"2021-02-26T14:35:10+00:00","dateModified":"2023-12-11T10:16:41+00:00","breadcrumb":{"@id":"https:\/\/lerevebeauty.it\/en\/glossary\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lerevebeauty.it\/en\/glossary\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lerevebeauty.it\/en\/glossary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lerevebeauty.it\/en\/"},{"@type":"ListItem","position":2,"name":"Glossary"}]},{"@type":"WebSite","@id":"https:\/\/lerevebeauty.it\/en\/#website","url":"https:\/\/lerevebeauty.it\/en\/","name":"Ler\u00e8ve","description":"Nutricosmetics &amp; Beauty","publisher":{"@id":"https:\/\/lerevebeauty.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lerevebeauty.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lerevebeauty.it\/en\/#organization","name":"Ler\u00e8ve","url":"https:\/\/lerevebeauty.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lerevebeauty.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lerevebeauty.it\/wp-content\/uploads\/2022\/03\/logo-lereve-senza-payoff.png","contentUrl":"https:\/\/lerevebeauty.it\/wp-content\/uploads\/2022\/03\/logo-lereve-senza-payoff.png","width":377,"height":110,"caption":"Ler\u00e8ve"},"image":{"@id":"https:\/\/lerevebeauty.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/pages\/3711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/comments?post=3711"}],"version-history":[{"count":1,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/pages\/3711\/revisions"}],"predecessor-version":[{"id":3716,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/pages\/3711\/revisions\/3716"}],"wp:attachment":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/media?parent=3711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}