{"id":261,"date":"2021-02-15T16:21:30","date_gmt":"2021-02-15T15:21:30","guid":{"rendered":"https:\/\/lerevebeauty.it\/?post_type=glossary&#038;p=261"},"modified":"2022-05-02T21:34:37","modified_gmt":"2022-05-02T20:34:37","slug":"triticum-vulgare-germ-oil-olio-di-germe-di-grano","status":"publish","type":"glossary","link":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/","title":{"rendered":"Triticum vulgare germ oil (Olio di Germe di Grano)"},"content":{"rendered":"<div id=\"modal-ready\">\n<p class=\"has-text-align-center wp-block-paragraph\">TRITICUM VULGARE GERM OIL (Olio di germe di grano)<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Idratante per la pelle, le unghie e i capelli. Anti-age. Ingrediente di origine naturale.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Lo trovi in: Timeless Beauty.<\/p>\n<\/div>","protected":false},"author":5,"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"_links_to":"","_links_to_target":""},"glossary-cat":[],"class_list":["post-261","glossary","type-glossary","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve\" \/>\n<meta property=\"og:description\" content=\"TRITICUM VULGARE GERM OIL (Olio di germe di grano) Idratante per la pelle, le unghie e i capelli. Anti-age. Ingrediente di origine naturale. Lo trovi in: Timeless Beauty.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ler\u00e8ve\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-02T20:34:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossario\\\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\\\/\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossario\\\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\\\/\",\"name\":\"Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#website\"},\"datePublished\":\"2021-02-15T15:21:30+00:00\",\"dateModified\":\"2022-05-02T20:34:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossario\\\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossario\\\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/glossario\\\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triticum vulgare germ oil (Olio di Germe di Grano)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\",\"name\":\"Ler\u00e8ve\",\"description\":\"Nutricosmetics &amp; Beauty\",\"publisher\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#organization\",\"name\":\"Ler\u00e8ve\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lerevebeauty.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo-lereve-senza-payoff.png\",\"contentUrl\":\"https:\\\/\\\/lerevebeauty.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo-lereve-senza-payoff.png\",\"width\":377,\"height\":110,\"caption\":\"Ler\u00e8ve\"},\"image\":{\"@id\":\"https:\\\/\\\/lerevebeauty.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/","og_locale":"en_US","og_type":"article","og_title":"Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve","og_description":"TRITICUM VULGARE GERM OIL (Olio di germe di grano) Idratante per la pelle, le unghie e i capelli. Anti-age. Ingrediente di origine naturale. Lo trovi in: Timeless Beauty.","og_url":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/","og_site_name":"Ler\u00e8ve","article_modified_time":"2022-05-02T20:34:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/","url":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/","name":"Triticum vulgare germ oil (Olio di Germe di Grano) - Ler\u00e8ve","isPartOf":{"@id":"https:\/\/lerevebeauty.it\/en\/#website"},"datePublished":"2021-02-15T15:21:30+00:00","dateModified":"2022-05-02T20:34:37+00:00","breadcrumb":{"@id":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lerevebeauty.it\/en\/glossario\/triticum-vulgare-germ-oil-olio-di-germe-di-grano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lerevebeauty.it\/en\/"},{"@type":"ListItem","position":2,"name":"Triticum vulgare germ oil (Olio di Germe di Grano)"}]},{"@type":"WebSite","@id":"https:\/\/lerevebeauty.it\/en\/#website","url":"https:\/\/lerevebeauty.it\/en\/","name":"Ler\u00e8ve","description":"Nutricosmetics &amp; Beauty","publisher":{"@id":"https:\/\/lerevebeauty.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lerevebeauty.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lerevebeauty.it\/en\/#organization","name":"Ler\u00e8ve","url":"https:\/\/lerevebeauty.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lerevebeauty.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lerevebeauty.it\/wp-content\/uploads\/2022\/03\/logo-lereve-senza-payoff.png","contentUrl":"https:\/\/lerevebeauty.it\/wp-content\/uploads\/2022\/03\/logo-lereve-senza-payoff.png","width":377,"height":110,"caption":"Ler\u00e8ve"},"image":{"@id":"https:\/\/lerevebeauty.it\/en\/#\/schema\/logo\/image\/"}}]}},"related_terms":"Triticum vulgare germ oil,Olio di Germe di Grano","external_url":"","internal_reference_id":"261","_links":{"self":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/glossary\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/glossary\/261\/revisions"}],"wp:attachment":[{"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/media?parent=261"}],"wp:term":[{"taxonomy":"glossary-cat","embeddable":true,"href":"https:\/\/lerevebeauty.it\/en\/wp-json\/wp\/v2\/glossary-cat?post=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}